{"id":3641,"date":"2022-07-15T09:00:22","date_gmt":"2022-07-15T13:00:22","guid":{"rendered":"https:\/\/hockeydieppememramcook.sharkmediasport.com\/?page_id=3641"},"modified":"2026-07-09T09:28:29","modified_gmt":"2026-07-09T13:28:29","slug":"m9","status":"publish","type":"page","link":"https:\/\/hockeydieppememramcook.ca\/en\/m9\/","title":{"rendered":"M9"},"content":{"rendered":"<p><strong>SAISON 2026-2027<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3643\" src=\"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg 200w, https:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar-150x150.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>M9 \u2013\u00a0 les pratiques vont commencer la semaine du 14 Octobre.\u00a0 Lorsque les \u00e9quipes seront fait, vous recevrez une invitation de Teamsnap pour vous joindre \u00e0 votre \u00e9quipe.<\/strong><\/p>\n<p><strong>Coordinateur division M9 :<\/strong>\u00a0<b><a href=\"mailto:ianawells@gmail.com\">Ian Wells<\/a> &#8211; 506-866-1192<\/b><\/p>\n<p><strong>Processus d&#8217;\u00e9valuation<\/strong><\/p>\n<h3>Philosophie du programme de hockey des M9<\/h3>\n<ul>\n<li>Hockey Canada a con\u00e7u le programme pour faire en sorte que les premi\u00e8res exp\u00e9riences au hockey des enfants soient s\u00e9curitaires et positives.<\/li>\n<li>Le programme permet aux participants de devenir des membres actifs au sein d&#8217;une \u00e9quipe, de d\u00e9velopper leur estime de soi et d&#8217;\u00e9prouver un sentiment d&#8217;accomplissement sur le plan personnel.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Buts du hockey des M9<\/h3>\n<ul>\n<li>S&#8217;amuser en jouant au hockey et en pratiquant une activit\u00e9 physique.<\/li>\n<li>Apprendre les habilet\u00e9s de base requises pour jouer au hockey.<\/li>\n<li>D\u00e9velopper et perfectionner les sch\u00e9mas moteurs de base.<\/li>\n<li>S&#8217;initier aux concepts de la coop\u00e9ration et du franc-jeu.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SAISON 2026-2027 &nbsp; M9 \u2013\u00a0 les pratiques vont commencer la semaine du 14 Octobre.\u00a0 Lorsque les \u00e9quipes seront fait, vous recevrez une invitation de Teamsnap pour vous joindre \u00e0 votre \u00e9quipe. Coordinateur division M9 :\u00a0Ian Wells &#8211; 506-866-1192 Processus d&#8217;\u00e9valuation Philosophie du programme de hockey des M9 Hockey Canada a con\u00e7u le programme pour faire [&hellip;]<\/p>\n","protected":false},"author":473,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3641","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M9 - Hockey Dieppe Memramcook<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hockeydieppememramcook.ca\/m9\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M9 - Hockey Dieppe Memramcook\" \/>\n<meta property=\"og:description\" content=\"SAISON 2026-2027 &nbsp; M9 \u2013\u00a0 les pratiques vont commencer la semaine du 14 Octobre.\u00a0 Lorsque les \u00e9quipes seront fait, vous recevrez une invitation de Teamsnap pour vous joindre \u00e0 votre \u00e9quipe. Coordinateur division M9 :\u00a0Ian Wells &#8211; 506-866-1192 Processus d&#8217;\u00e9valuation Philosophie du programme de hockey des M9 Hockey Canada a con\u00e7u le programme pour faire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hockeydieppememramcook.ca\/m9\/\" \/>\n<meta property=\"og:site_name\" content=\"Hockey Dieppe Memramcook\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T13:28:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hockeydieppememramcook.ca\/m9\/\",\"url\":\"https:\/\/hockeydieppememramcook.ca\/m9\/\",\"name\":\"M9 - Hockey Dieppe Memramcook\",\"isPartOf\":{\"@id\":\"https:\/\/hockeydieppememramcook.ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hockeydieppememramcook.ca\/m9\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hockeydieppememramcook.ca\/m9\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg\",\"datePublished\":\"2022-07-15T13:00:22+00:00\",\"dateModified\":\"2026-07-09T13:28:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hockeydieppememramcook.ca\/m9\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hockeydieppememramcook.ca\/m9\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hockeydieppememramcook.ca\/m9\/#primaryimage\",\"url\":\"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg\",\"contentUrl\":\"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hockeydieppememramcook.ca\/m9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/hockeydieppememramcook.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hockeydieppememramcook.ca\/#website\",\"url\":\"https:\/\/hockeydieppememramcook.ca\/\",\"name\":\"Hockey Dieppe Memramcook\",\"description\":\"Un site utilisant Les sites de Shark M\u00e9dia & Sport, template Slapshot\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hockeydieppememramcook.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M9 - Hockey Dieppe Memramcook","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hockeydieppememramcook.ca\/m9\/","og_locale":"en_US","og_type":"article","og_title":"M9 - Hockey Dieppe Memramcook","og_description":"SAISON 2026-2027 &nbsp; M9 \u2013\u00a0 les pratiques vont commencer la semaine du 14 Octobre.\u00a0 Lorsque les \u00e9quipes seront fait, vous recevrez une invitation de Teamsnap pour vous joindre \u00e0 votre \u00e9quipe. Coordinateur division M9 :\u00a0Ian Wells &#8211; 506-866-1192 Processus d&#8217;\u00e9valuation Philosophie du programme de hockey des M9 Hockey Canada a con\u00e7u le programme pour faire [&hellip;]","og_url":"https:\/\/hockeydieppememramcook.ca\/m9\/","og_site_name":"Hockey Dieppe Memramcook","article_modified_time":"2026-07-09T13:28:29+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hockeydieppememramcook.ca\/m9\/","url":"https:\/\/hockeydieppememramcook.ca\/m9\/","name":"M9 - Hockey Dieppe Memramcook","isPartOf":{"@id":"https:\/\/hockeydieppememramcook.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hockeydieppememramcook.ca\/m9\/#primaryimage"},"image":{"@id":"https:\/\/hockeydieppememramcook.ca\/m9\/#primaryimage"},"thumbnailUrl":"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg","datePublished":"2022-07-15T13:00:22+00:00","dateModified":"2026-07-09T13:28:29+00:00","breadcrumb":{"@id":"https:\/\/hockeydieppememramcook.ca\/m9\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hockeydieppememramcook.ca\/m9\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hockeydieppememramcook.ca\/m9\/#primaryimage","url":"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg","contentUrl":"http:\/\/hockeydieppememramcook.ca\/wp-content\/uploads\/sites\/527\/2022\/07\/system_calendar.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/hockeydieppememramcook.ca\/m9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hockeydieppememramcook.ca\/en\/"},{"@type":"ListItem","position":2,"name":"M9"}]},{"@type":"WebSite","@id":"https:\/\/hockeydieppememramcook.ca\/#website","url":"https:\/\/hockeydieppememramcook.ca\/","name":"Hockey Dieppe Memramcook","description":"Un site utilisant Les sites de Shark M\u00e9dia & Sport, template Slapshot","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hockeydieppememramcook.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/pages\/3641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/users\/473"}],"replies":[{"embeddable":true,"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/comments?post=3641"}],"version-history":[{"count":13,"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/pages\/3641\/revisions"}],"predecessor-version":[{"id":9171,"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/pages\/3641\/revisions\/9171"}],"wp:attachment":[{"href":"https:\/\/hockeydieppememramcook.ca\/en\/wp-json\/wp\/v2\/media?parent=3641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}